{"id":26531,"date":"2021-07-31T22:46:29","date_gmt":"2021-07-31T22:46:29","guid":{"rendered":"https:\/\/redfoxlotto.com\/?p=26531"},"modified":"2021-08-02T15:21:11","modified_gmt":"2021-08-02T14:21:11","slug":"la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces","status":"publish","type":"post","link":"https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/","title":{"rendered":"Esta se\u00f1ora de la limpieza gan\u00f3 el bote de la Thunderball dos veces"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A lo largo de los a\u00f1os ha habido muchas personas que han ganado botes de la Loter\u00eda. Gayle Say, una limpiadora de 65 a\u00f1os de Coventry, gan\u00f3 1 mill\u00f3n de libras esterlinas en el bote de la loter\u00eda Thunderball dos veces. Ella y su marido, Philip Say, llevaban 25 a\u00f1os jugando a la loter\u00eda con s\u00f3lo unos pocos premios de 10 libras. Pero en un golpe de suerte, no s\u00f3lo ganaron un bote de 500.000 libras, sino dos.<\/p><p class=\"wp-block-paragraph\">Ganar dos veces fue posible porque Gayle compr\u00f3 boletos que ten\u00edan los mismos n\u00fameros ganadores. Dice que fue un error y que estuvo a punto de cancelar el segundo boleto. Pero decidi\u00f3 no cancelar el segundo boleto.<\/p><h2 class=\"wp-block-heading\">Ganar el Jjckpot le permiti\u00f3 jubilarse anticipadamente<\/h2><p><img decoding=\"async\" class=\"size-full wp-image alignright\" src=\"https:\/\/redfoxlotto.com\/wp-content\/uploads\/sites\/9\/1_dollar_win_online.jpg\" alt=\"bote\"><\/p><p class=\"wp-block-paragraph\">Antes de ganar el bote, Gayle trabajaba en la limpieza. Seg\u00fan Gayle, ten\u00eda que ir a trabajar desde las 6 de la ma\u00f1ana seis d\u00edas a la semana. Hab\u00eda trabajado mucho durante la mayor parte de su vida y estaba contenta por la posibilidad de jubilarse.<\/p><p class=\"wp-block-paragraph\">Sin embargo, para la pareja, ganar significaba poder ayudar a sus hijos y nietos. Philip pensaba comprarse un coche, ya que nunca hab\u00eda tenido uno. Adem\u00e1s, iba a comprar un coche espacioso porque sus nietos se quedaban con ellos dos veces por semana.<\/p><p class=\"wp-block-paragraph\">Su historia inspir\u00f3 a mucha gente. Aunque hab\u00edan jugado a la loter\u00eda durante mucho tiempo, nunca perdieron la esperanza. Sab\u00edan que cualquier d\u00eda pod\u00eda tocarles el premio gordo. Adem\u00e1s, ganar el premio gordo significaba mucho para ellos, m\u00e1s all\u00e1 de lo que disfrutar\u00edan personalmente. La oportunidad de ayudar a sus hijos y nietos hac\u00eda feliz a la pareja.<\/p><h2 class=\"wp-block-heading\">Jugar a la loter\u00eda para ganar<\/h2><p class=\"wp-block-paragraph\">Un elemento clave para jugar a la loter\u00eda es la creencia de que se puede ganar. Al menos, esto es algo en lo que coinciden la mayor\u00eda de los ganadores de loter\u00eda. Gayle y Philip Say no dejaron de creer que pod\u00edan ganar el premio gordo. S\u00ed, jugar a la loter\u00eda es sobre todo suerte, porque es un juego de azar. Sin embargo, la mayor\u00eda de la gente cree que el universo tiene una forma de recompensar la fe.<\/p><p class=\"wp-block-paragraph\">Adem\u00e1s, lo que parece un error puede jugar a su favor. As\u00ed que, aunque no hayas elegido los n\u00fameros que quer\u00edas, puedes ganar. Cuando Gayle eligi\u00f3 el segundo boleto, podr\u00eda haberlo anulado. En lugar de eso, decidi\u00f3 conservarlo y lo que parec\u00eda un error result\u00f3 ser un premio de 1 mill\u00f3n de libras.<\/p><p class=\"wp-block-paragraph\">Lo bueno de jugar a la loter\u00eda es que nunca sabes cu\u00e1ndo la suerte se pondr\u00e1 a tu favor.<\/p><h2 class=\"wp-block-heading\">C\u00f3mo ganaron el bote dos veces y consiguieron 1 mill\u00f3n de libras<\/h2><p class=\"wp-block-paragraph\">Gayle y Philip Say ganaron 1 mill\u00f3n de libras esterlinas jugando a la loter\u00eda, pero esto no funciona en todas las loter\u00edas. S\u00f3lo pudo ocurrir as\u00ed porque jugaron a la loter\u00eda Thunderball. Las reglas de la Thunderball permiten que cualquiera que tenga un boleto ganador pueda reclamar el bote. Y los ganadores no tienen que compartir el Jackpot. Cada ganador se va a casa con el premio de 500.000 libras.<\/p><p class=\"wp-block-paragraph\">Como la pareja ten\u00eda dos boletos ganadores, pudieron ganar dos premios mayores de 500.000 libras cada uno. Por lo tanto, si va a comprar varios boletos, es una buena idea elegir cuidadosamente la loter\u00eda a la que juega. Los juegos como Thunderball son atractivos porque si ganas el bote te vas a casa con la cantidad completa. Incluso si hay otros ganadores.<\/p><p class=\"wp-block-paragraph\">Gayle y Philip Say ganaron 1 mill\u00f3n de libras con dos boletos ganadores. Podr\u00edas ser la pr\u00f3xima persona en ganar el bote. Pero no puede ganar si no juega. As\u00ed que, \u00bfpor qu\u00e9 no comprar un boleto hoy? Puede comprar m\u00e1s de uno y \u00bfqui\u00e9n sabe qu\u00e9 pasar\u00e1? Puede consultar nuestra lista de loter\u00edas en este sitio web para encontrar el juego adecuado para usted.<\/p>","protected":false},"excerpt":{"rendered":"<p>A lo largo de los a\u00f1os ha habido muchas personas que han ganado botes de la Loter\u00eda. Gayle Say, una limpiadora de 65 a\u00f1os de Coventry, gan\u00f3 1 mill\u00f3n de libras esterlinas en el bote de la loter\u00eda Thunderball dos veces. Ella y su marido, Philip Say, llevaban 25 a\u00f1os jugando a la loter\u00eda con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1094],"tags":[],"class_list":["post-26531","post","type-post","status-publish","format-standard","hentry","category-winner-stories-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Esta se\u00f1ora de la limpieza ha ganado el bote de la Thunderball dos veces<\/title>\n<meta name=\"description\" content=\"\u00bfTe preguntas si hay gente que ha ganado la loter\u00eda? Lea la inspiradora historia de la se\u00f1ora de la limpieza que gan\u00f3 el bote de la Thunderball dos veces\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esta se\u00f1ora de la limpieza ha ganado el bote de la Thunderball dos veces\" \/>\n<meta property=\"og:description\" content=\"\u00bfTe preguntas si hay gente que ha ganado la loter\u00eda? Lea la inspiradora historia de la se\u00f1ora de la limpieza que gan\u00f3 el bote de la Thunderball dos veces\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/\" \/>\n<meta property=\"og:site_name\" content=\"Get Tickets for the World\u2019s largest jackpots\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-31T22:46:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-02T14:21:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redfoxlotto.com\/wp-content\/uploads\/sites\/9\/1_dollar_win_online.jpg\" \/>\n<meta name=\"author\" content=\"Catfish\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Catfish\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\\\/\"},\"author\":{\"name\":\"Catfish\",\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/#\\\/schema\\\/person\\\/118a644a90782952c5d80744e5bd2fbd\"},\"headline\":\"Esta se\u00f1ora de la limpieza gan\u00f3 el bote de la Thunderball dos veces\",\"datePublished\":\"2021-07-31T22:46:29+00:00\",\"dateModified\":\"2021-08-02T14:21:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\\\/\"},\"wordCount\":694,\"publisher\":{\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redfoxlotto.com\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/1_dollar_win_online.jpg\",\"articleSection\":[\"Winner Stories\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\\\/\",\"url\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\\\/\",\"name\":\"Esta se\u00f1ora de la limpieza ha ganado el bote de la Thunderball dos veces\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redfoxlotto.com\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/1_dollar_win_online.jpg\",\"datePublished\":\"2021-07-31T22:46:29+00:00\",\"dateModified\":\"2021-08-02T14:21:11+00:00\",\"description\":\"\u00bfTe preguntas si hay gente que ha ganado la loter\u00eda? Lea la inspiradora historia de la se\u00f1ora de la limpieza que gan\u00f3 el bote de la Thunderball dos veces\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redfoxlotto.com\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/1_dollar_win_online.jpg\",\"contentUrl\":\"https:\\\/\\\/redfoxlotto.com\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/1_dollar_win_online.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esta se\u00f1ora de la limpieza gan\u00f3 el bote de la Thunderball dos veces\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/\",\"name\":\"Get Tickets for the World\u2019s largest jackpots\",\"description\":\"Participate in worldwide lottery jackpots from any country\",\"publisher\":{\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/#organization\",\"name\":\"Get Tickets for the World\u2019s largest jackpots\",\"url\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redfoxlotto.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/redfoxlotto.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo.png\",\"width\":269,\"height\":53,\"caption\":\"Get Tickets for the World\u2019s largest jackpots\"},\"image\":{\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/#\\\/schema\\\/person\\\/118a644a90782952c5d80744e5bd2fbd\",\"name\":\"Catfish\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32edfa28ccbf005c231538b245a2670a36c7f33f2d3a9ab09e50843b363f2821?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32edfa28ccbf005c231538b245a2670a36c7f33f2d3a9ab09e50843b363f2821?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32edfa28ccbf005c231538b245a2670a36c7f33f2d3a9ab09e50843b363f2821?s=96&d=mm&r=g\",\"caption\":\"Catfish\"},\"sameAs\":[\"https:\\\/\\\/www.redfoxlotto.eu\"],\"url\":\"https:\\\/\\\/redfoxlotto.com\\\/es\\\/author\\\/catfish\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esta se\u00f1ora de la limpieza ha ganado el bote de la Thunderball dos veces","description":"\u00bfTe preguntas si hay gente que ha ganado la loter\u00eda? Lea la inspiradora historia de la se\u00f1ora de la limpieza que gan\u00f3 el bote de la Thunderball dos veces","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/","og_locale":"es_ES","og_type":"article","og_title":"Esta se\u00f1ora de la limpieza ha ganado el bote de la Thunderball dos veces","og_description":"\u00bfTe preguntas si hay gente que ha ganado la loter\u00eda? Lea la inspiradora historia de la se\u00f1ora de la limpieza que gan\u00f3 el bote de la Thunderball dos veces","og_url":"https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/","og_site_name":"Get Tickets for the World\u2019s largest jackpots","article_published_time":"2021-07-31T22:46:29+00:00","article_modified_time":"2021-08-02T14:21:11+00:00","og_image":[{"url":"https:\/\/redfoxlotto.com\/wp-content\/uploads\/sites\/9\/1_dollar_win_online.jpg","type":"","width":"","height":""}],"author":"Catfish","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Catfish","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/#article","isPartOf":{"@id":"https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/"},"author":{"name":"Catfish","@id":"https:\/\/redfoxlotto.com\/es\/#\/schema\/person\/118a644a90782952c5d80744e5bd2fbd"},"headline":"Esta se\u00f1ora de la limpieza gan\u00f3 el bote de la Thunderball dos veces","datePublished":"2021-07-31T22:46:29+00:00","dateModified":"2021-08-02T14:21:11+00:00","mainEntityOfPage":{"@id":"https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/"},"wordCount":694,"publisher":{"@id":"https:\/\/redfoxlotto.com\/es\/#organization"},"image":{"@id":"https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/#primaryimage"},"thumbnailUrl":"https:\/\/redfoxlotto.com\/wp-content\/uploads\/sites\/9\/1_dollar_win_online.jpg","articleSection":["Winner Stories"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/","url":"https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/","name":"Esta se\u00f1ora de la limpieza ha ganado el bote de la Thunderball dos veces","isPartOf":{"@id":"https:\/\/redfoxlotto.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/#primaryimage"},"image":{"@id":"https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/#primaryimage"},"thumbnailUrl":"https:\/\/redfoxlotto.com\/wp-content\/uploads\/sites\/9\/1_dollar_win_online.jpg","datePublished":"2021-07-31T22:46:29+00:00","dateModified":"2021-08-02T14:21:11+00:00","description":"\u00bfTe preguntas si hay gente que ha ganado la loter\u00eda? Lea la inspiradora historia de la se\u00f1ora de la limpieza que gan\u00f3 el bote de la Thunderball dos veces","breadcrumb":{"@id":"https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/#primaryimage","url":"https:\/\/redfoxlotto.com\/wp-content\/uploads\/sites\/9\/1_dollar_win_online.jpg","contentUrl":"https:\/\/redfoxlotto.com\/wp-content\/uploads\/sites\/9\/1_dollar_win_online.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/redfoxlotto.com\/es\/la-senora-de-la-limpieza-gana-el-bote-de-la-thunderball-dos-veces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/redfoxlotto.com\/es\/"},{"@type":"ListItem","position":2,"name":"Esta se\u00f1ora de la limpieza gan\u00f3 el bote de la Thunderball dos veces"}]},{"@type":"WebSite","@id":"https:\/\/redfoxlotto.com\/es\/#website","url":"https:\/\/redfoxlotto.com\/es\/","name":"Get Tickets for the World\u2019s largest jackpots","description":"Participate in worldwide lottery jackpots from any country","publisher":{"@id":"https:\/\/redfoxlotto.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redfoxlotto.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/redfoxlotto.com\/es\/#organization","name":"Get Tickets for the World\u2019s largest jackpots","url":"https:\/\/redfoxlotto.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redfoxlotto.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/redfoxlotto.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/redfoxlotto.com\/wp-content\/uploads\/2023\/04\/logo.png","width":269,"height":53,"caption":"Get Tickets for the World\u2019s largest jackpots"},"image":{"@id":"https:\/\/redfoxlotto.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redfoxlotto.com\/es\/#\/schema\/person\/118a644a90782952c5d80744e5bd2fbd","name":"Catfish","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/32edfa28ccbf005c231538b245a2670a36c7f33f2d3a9ab09e50843b363f2821?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32edfa28ccbf005c231538b245a2670a36c7f33f2d3a9ab09e50843b363f2821?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32edfa28ccbf005c231538b245a2670a36c7f33f2d3a9ab09e50843b363f2821?s=96&d=mm&r=g","caption":"Catfish"},"sameAs":["https:\/\/www.redfoxlotto.eu"],"url":"https:\/\/redfoxlotto.com\/es\/author\/catfish\/"}]}},"_links":{"self":[{"href":"https:\/\/redfoxlotto.com\/es\/wp-json\/wp\/v2\/posts\/26531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redfoxlotto.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redfoxlotto.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redfoxlotto.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redfoxlotto.com\/es\/wp-json\/wp\/v2\/comments?post=26531"}],"version-history":[{"count":0,"href":"https:\/\/redfoxlotto.com\/es\/wp-json\/wp\/v2\/posts\/26531\/revisions"}],"wp:attachment":[{"href":"https:\/\/redfoxlotto.com\/es\/wp-json\/wp\/v2\/media?parent=26531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redfoxlotto.com\/es\/wp-json\/wp\/v2\/categories?post=26531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redfoxlotto.com\/es\/wp-json\/wp\/v2\/tags?post=26531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}